{"id":12308,"date":"2026-02-23T14:57:13","date_gmt":"2026-02-23T13:57:13","guid":{"rendered":"https:\/\/fifes.org\/walking-in-the-dark\/"},"modified":"2026-03-03T18:47:43","modified_gmt":"2026-03-03T17:47:43","slug":"walking-in-the-dark","status":"publish","type":"page","link":"https:\/\/fifes.org\/en\/walking-in-the-dark\/","title":{"rendered":"Walking in the dark"},"content":{"rendered":"<p><div class=\"et_pb_with_border et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Walking in the dark<\/span><\/span><\/h1>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>International competition<br \/><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Saturday, May 30, 10:30 a.m.<\/span> - Espace Miramar  <\/strong><\/span><\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_2_5 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"1051\" src=\"\/wp-content\/uploads\/2026\/02\/marcher-dans-l-obscurite.jpg\" alt=\"\" title=\"walk-in-darkness\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/marcher-dans-l-obscurite.jpg 700w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/marcher-dans-l-obscurite-480x721.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" class=\"wp-image-12318\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_3_5 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong><span style=\"color: #000000;\">Kinshuk Surjan<br \/>Documentary - 108 min - Belgium, Netherlands, India - 2024<br \/>VO in Hindi, subtitled in French<\/span><br \/><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong><span style=\"color: #000000;\"><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: #000000;\">Determined to provide a better life for herself and her children after the suicide of her farmer husband, Sanjivani struggles against the traditional abandonment of widows in her culture, until she joins a discussion group with other widows of farmers who have died by suicide. With the support of her community, shared stories of resilience and unexpected solidarity, Sanjivani cautiously plots her path towards the future. <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong><span style=\"color: #000000;\"><\/span><\/strong><\/span><\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_video et_pb_video_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_video_box\"><iframe loading=\"lazy\" title=\"Marching in the dark - Marcher dans l&amp;apos;obscurit\u00e9 (Kinshuk Surjan, 2024) TRAILER\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/M35T0b0ojj0?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element dnxte_coverflowslider_parent dnxte_coverflowslider_parent_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"et_pb_module et_d4_element dnxte_coverflowslider_parent dnxte_coverflowslider_parent_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"coverflow-container  arrow-position-bottom\">\r\n                <div class=\"swiper-container dnxte-coverflowslider-active swiper-container-initialized swiper-container-horizontal \" data-autoplay=\"1\" data-delay=\"2000\" data-direction=\"horizontal\" data-speed=\"400\" data-loop=\"on\" data-pagination-type=\"bullets\" data-pagination-bullets=\"on\"   data-breakpoints=\"6|1|1\" data-spacing=\"15\" data-grab=\"off\" data-center=\"\" data-keyboardenable=\"on\"  data-covershadow=\"off\" data-coverrotate=\"0\" data-coverstretch=\"0\" data-coverdepth=\"0\" data-autoheight=\"off\" data-pauseonhover=\"1\" data-mouse=\"on\">\r\n                    <div class=\"swiper-wrapper\" data-lightbox=\"off\" data-orderclass=\"dnxte_coverflowslider_parent_0\">\r\n                        <div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_0 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/au-bout-des-mots-affiche-film.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/au-bout-des-mots\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"674\" height=\"954\" src=\"\/wp-content\/uploads\/2026\/02\/au-bout-des-mots-affiche-film.jpg\" alt=\"Au bout des mots\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/au-bout-des-mots-affiche-film.jpg 674w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/au-bout-des-mots-affiche-film-480x679.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 674px, 100vw\" class=\"wp-image-12395 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_1 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/Foret-rouge-vignette.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/foret-rouge\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"425\" src=\"\/wp-content\/uploads\/2026\/02\/Foret-rouge-vignette.jpg\" alt=\"Foret rouge\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/Foret-rouge-vignette.jpg 300w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/Foret-rouge-vignette-212x300.jpg 212w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-12547 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_2 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/affiche-le-ciel-au-dessus-de-zenica.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/le-ciel-au-dessus-de-zenica\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"686\" height=\"979\" src=\"\/wp-content\/uploads\/2026\/02\/affiche-le-ciel-au-dessus-de-zenica.jpg\" alt=\"le-ciel-au-dessus-de-zenica\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/affiche-le-ciel-au-dessus-de-zenica.jpg 686w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/affiche-le-ciel-au-dessus-de-zenica-480x685.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 686px, 100vw\" class=\"wp-image-12392 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_3 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/Ojos-de-Agua-vignette.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/ojos-de-agua\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"425\" src=\"\/wp-content\/uploads\/2026\/02\/Ojos-de-Agua-vignette.jpg\" alt=\"Ojos de Agua\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/Ojos-de-Agua-vignette.jpg 300w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/Ojos-de-Agua-vignette-212x300.jpg 212w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-12548 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_4 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/cocotte-vignette.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/cocotte\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"425\" src=\"\/wp-content\/uploads\/2026\/02\/cocotte-vignette.jpg\" alt=\"Cocotte\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/cocotte-vignette.jpg 300w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/cocotte-vignette-212x300.jpg 212w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-12549 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_5 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/marcher-dans-l-obscurite-vignette.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/marcher-dans-lobscurite\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"425\" src=\"\/wp-content\/uploads\/2026\/02\/marcher-dans-l-obscurite-vignette.jpg\" alt=\"Marcher dans l\u2019obscurit\u00e9\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/marcher-dans-l-obscurite-vignette.jpg 300w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/marcher-dans-l-obscurite-vignette-212x300.jpg 212w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-12550 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_6 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/une-chanson-pour-ma-terre.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/une-chanson-pour-ma-terre\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"990\" src=\"\/wp-content\/uploads\/2026\/02\/une-chanson-pour-ma-terre.jpg\" alt=\"Une chanson pour ma terre\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/une-chanson-pour-ma-terre.jpg 700w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/une-chanson-pour-ma-terre-480x679.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 700px, 100vw\" class=\"wp-image-12362 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_7 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/Yanuni-affiche-film.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/yanuni,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"903\" src=\"\/wp-content\/uploads\/2026\/02\/Yanuni-affiche-film.jpg\" alt=\"Yanuni\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/Yanuni-affiche-film.jpg 645w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/Yanuni-affiche-film-480x672.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 645px, 100vw\" class=\"wp-image-12394 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_8 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/Yintah-vignette.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/yintah\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"425\" src=\"\/wp-content\/uploads\/2026\/02\/Yintah-vignette.jpg\" alt=\"Yintah\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/Yintah-vignette.jpg 300w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/Yintah-vignette-212x300.jpg 212w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-12551 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_9 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/nimuendaju-vignette.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/nimuendaju\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"425\" src=\"\/wp-content\/uploads\/2026\/02\/nimuendaju-vignette.jpg\" alt=\"Nimuendaj\u00fa\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/nimuendaju-vignette.jpg 300w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/nimuendaju-vignette-212x300.jpg 212w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-12552 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_10 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/heidi-vignette.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/heidi\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"425\" src=\"\/wp-content\/uploads\/2026\/02\/heidi-vignette.jpg\" alt=\"Heidi et le lynx des montagnes\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/heidi-vignette.jpg 300w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/heidi-vignette-212x300.jpg 212w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"wp-image-12544 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_11 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2026\/02\/mercantour.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/mercantour-sous-nos-pieds\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"268\" height=\"380\" src=\"\/wp-content\/uploads\/2026\/02\/mercantour.jpg\" alt=\"Mercantour sous nos pieds\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/mercantour.jpg 268w, https:\/\/fifes.org\/wp-content\/uploads\/2026\/02\/mercantour-212x300.jpg 212w\" sizes=\"(max-width: 268px) 100vw, 268px\" class=\"wp-image-12513 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\r\n                    <\/div>\r\n                    <div class=\"swiper-pagination swiper-pagination-clickable swiper-pagination-bullets swiper-pagination-bullets-dynamic mt-10\"><\/div>\r\n                <\/div>\r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-12308","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Walking in the dark - Fifes - Festival Internation du Film Ecologique et Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fifes.org\/marcher-dans-lobscurite\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Walking in the dark - Fifes - Festival Internation du Film Ecologique et Social\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fifes.org\/marcher-dans-lobscurite\/\" \/>\n<meta property=\"og:site_name\" content=\"Fifes - Festival Internation du Film Ecologique et Social\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fifescannes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T17:47:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fifes.org\\\/marcher-dans-lobscurite\\\/\",\"url\":\"https:\\\/\\\/fifes.org\\\/marcher-dans-lobscurite\\\/\",\"name\":\"Walking in the dark - Fifes - Festival Internation du Film Ecologique et Social\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fifes.org\\\/#website\"},\"datePublished\":\"2026-02-23T13:57:13+00:00\",\"dateModified\":\"2026-03-03T17:47:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fifes.org\\\/marcher-dans-lobscurite\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fifes.org\\\/marcher-dans-lobscurite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fifes.org\\\/marcher-dans-lobscurite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fifes.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Walking in the dark\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fifes.org\\\/#website\",\"url\":\"https:\\\/\\\/fifes.org\\\/\",\"name\":\"Fifes - Festival Internation du Film Ecologique et Social\",\"description\":\"Venez \u00e0 la rencontre d\u2019un festival qui vous ressemble et qui nous rassemble !\",\"publisher\":{\"@id\":\"https:\\\/\\\/fifes.org\\\/#organization\"},\"alternateName\":\"F.I.F.E.S.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fifes.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fifes.org\\\/#organization\",\"name\":\"Festival International du Film Ecologique et Social\",\"alternateName\":\"F.I.F.E.S.\",\"url\":\"https:\\\/\\\/fifes.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fifes.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fifes.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Logo-2023-480px-e1671803170434.png\",\"contentUrl\":\"https:\\\/\\\/fifes.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Logo-2023-480px-e1671803170434.png\",\"width\":200,\"height\":188,\"caption\":\"Festival International du Film Ecologique et Social\"},\"image\":{\"@id\":\"https:\\\/\\\/fifes.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fifescannes\",\"https:\\\/\\\/www.instagram.com\\\/fifescannes\\\/?hl=fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Walking in the dark - Fifes - Festival Internation du Film Ecologique et Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fifes.org\/marcher-dans-lobscurite\/","og_locale":"en_US","og_type":"article","og_title":"Walking in the dark - Fifes - Festival Internation du Film Ecologique et Social","og_url":"https:\/\/fifes.org\/marcher-dans-lobscurite\/","og_site_name":"Fifes - Festival Internation du Film Ecologique et Social","article_publisher":"https:\/\/www.facebook.com\/fifescannes","article_modified_time":"2026-03-03T17:47:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fifes.org\/marcher-dans-lobscurite\/","url":"https:\/\/fifes.org\/marcher-dans-lobscurite\/","name":"Walking in the dark - Fifes - Festival Internation du Film Ecologique et Social","isPartOf":{"@id":"https:\/\/fifes.org\/#website"},"datePublished":"2026-02-23T13:57:13+00:00","dateModified":"2026-03-03T17:47:43+00:00","breadcrumb":{"@id":"https:\/\/fifes.org\/marcher-dans-lobscurite\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fifes.org\/marcher-dans-lobscurite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fifes.org\/marcher-dans-lobscurite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fifes.org\/en\/"},{"@type":"ListItem","position":2,"name":"Walking in the dark"}]},{"@type":"WebSite","@id":"https:\/\/fifes.org\/#website","url":"https:\/\/fifes.org\/","name":"Fifes - Festival Internation du Film Ecologique et Social","description":"Venez \u00e0 la rencontre d\u2019un festival qui vous ressemble et qui nous rassemble !","publisher":{"@id":"https:\/\/fifes.org\/#organization"},"alternateName":"F.I.F.E.S.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fifes.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fifes.org\/#organization","name":"Festival International du Film Ecologique et Social","alternateName":"F.I.F.E.S.","url":"https:\/\/fifes.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fifes.org\/#\/schema\/logo\/image\/","url":"https:\/\/fifes.org\/wp-content\/uploads\/2022\/12\/Logo-2023-480px-e1671803170434.png","contentUrl":"https:\/\/fifes.org\/wp-content\/uploads\/2022\/12\/Logo-2023-480px-e1671803170434.png","width":200,"height":188,"caption":"Festival International du Film Ecologique et Social"},"image":{"@id":"https:\/\/fifes.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fifescannes","https:\/\/www.instagram.com\/fifescannes\/?hl=fr"]}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages\/12308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/comments?post=12308"}],"version-history":[{"count":10,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages\/12308\/revisions"}],"predecessor-version":[{"id":12640,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages\/12308\/revisions\/12640"}],"wp:attachment":[{"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/media?parent=12308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}