{"id":10942,"date":"2025-01-24T15:00:31","date_gmt":"2025-01-24T14:00:31","guid":{"rendered":"https:\/\/fifes.org\/international-competition\/documerica-self-portrait-of-a-nation-on-the-brink-of-the-abyss\/"},"modified":"2025-05-14T18:10:34","modified_gmt":"2025-05-14T16:10:34","slug":"documerica-self-portrait-of-a-nation-on-the-brink-of-the-abyss","status":"publish","type":"page","link":"https:\/\/fifes.org\/en\/international-competition\/documerica-self-portrait-of-a-nation-on-the-brink-of-the-abyss\/","title":{"rendered":"Documerica, self-portrait of a nation on the brink of the abyss"},"content":{"rendered":"<p><div class=\"et_pb_with_border et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular section_has_divider et_pb_bottom_divider et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Documerica, self-portrait of a nation on the brink of the abyss<\/span><\/h1>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>International competition<br \/>Saturday, May 31, 2pm - Espace Miramar<\/strong><\/span><\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_2_5 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Documerica-autoportrait-dune-nation-au-bord-de-labime-1.jpg\" alt=\"\" title=\"Documerica, self-portrait of a nation on the brink of the abyss\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Documerica-autoportrait-dune-nation-au-bord-de-labime-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Documerica-autoportrait-dune-nation-au-bord-de-labime-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8544\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_3_5 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong><span style=\"color: #000000;\">Pierre-Fran\u00e7ois DIDEK, France<br \/>67 min. - 2023 - Documentary - Les Films en Vrac <\/span><br \/><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong><span style=\"color: #000000;\"><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In the autumn of their lives, a group of photographers return to the Documerica Project, a gigantic photographic survey of the American environment commissioned by the government in the early 70s, at the height of ecological awareness. Embodying the moment of truth of a country that had reached the end of its American Dream, Documerica's images bear witness to a failed rendezvous with history. Beyond that, they speak to the world we live in today.  <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong><span style=\"color: #000000;\"><\/span><\/strong><\/span><\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_video et_pb_video_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_video_box\"><iframe loading=\"lazy\" title=\"Documerica - BCEFF 2023 OFFICIAL SELECTION\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/IL1O8-HEG8U?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element dnxte_coverflowslider_parent dnxte_coverflowslider_parent_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"et_pb_module et_d4_element dnxte_coverflowslider_parent dnxte_coverflowslider_parent_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"coverflow-container  arrow-position-bottom\">\r\n                <div class=\"swiper-container dnxte-coverflowslider-active swiper-container-initialized swiper-container-horizontal \" data-autoplay=\"1\" data-delay=\"2000\" data-direction=\"horizontal\" data-speed=\"400\" data-loop=\"on\" data-pagination-type=\"bullets\" data-pagination-bullets=\"on\"   data-breakpoints=\"6|1|1\" data-spacing=\"15\" data-grab=\"off\" data-center=\"\" data-keyboardenable=\"on\"  data-covershadow=\"off\" data-coverrotate=\"0\" data-coverstretch=\"0\" data-coverdepth=\"0\" data-autoheight=\"off\" data-pauseonhover=\"1\" data-mouse=\"on\">\r\n                    <div class=\"swiper-wrapper\" data-lightbox=\"off\" data-orderclass=\"dnxte_coverflowslider_parent_0\">\r\n                        <div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_0 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Il-etait-une-fois-dans-une-foret.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/il-etait-une-fois-dans-une-foret\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Il-etait-une-fois-dans-une-foret.jpg\" alt=\"Once upon a time\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Il-etait-une-fois-dans-une-foret.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Il-etait-une-fois-dans-une-foret-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8652 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_1 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Evil-Does-Not-Exist.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/le-mal-n-existe-pas\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Evil-Does-Not-Exist.jpg\" alt=\"Evil does not exist\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Evil-Does-Not-Exist.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Evil-Does-Not-Exist-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8557 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_2 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Anais-2-chapitres.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/anais-2-chapitres\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Anais-2-chapitres.jpg\" alt=\"Anais\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Anais-2-chapitres.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Anais-2-chapitres-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8526 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_3 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Les-papillons-noirs.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/les-papillons-noirs\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Les-papillons-noirs.jpg\" alt=\"papillons noirs\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Les-papillons-noirs.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Les-papillons-noirs-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8650 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_4 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/La-saveur-dune-vie-.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/la-saveur-d-une-vie\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/La-saveur-dune-vie-.jpg\" alt=\"la saveur d&#039;une vie\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/La-saveur-dune-vie-.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/La-saveur-dune-vie--212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8528 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_5 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Oceania-1.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/oceania\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Oceania-1.jpg\" alt=\"Oceania\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Oceania-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Oceania-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8546 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_6 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Les-Courants-Paralleles-1.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/les-courants-paralleles\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Les-Courants-Paralleles-1.jpg\" alt=\"courants\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Les-Courants-Paralleles-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Les-Courants-Paralleles-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8530 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_7 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Des-enfants-et-des-arbres-1.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/des-enfants-et-des-arbres\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Des-enfants-et-des-arbres-1.jpg\" alt=\"des enfants et de arbres\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Des-enfants-et-des-arbres-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Des-enfants-et-des-arbres-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8542 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_8 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Le-miroir-du-cosmos-1.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/le-miroir-du-cosmos\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Le-miroir-du-cosmos-1.jpg\" alt=\"a mirror of the cosmos\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Le-miroir-du-cosmos-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Le-miroir-du-cosmos-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8540 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_9 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Silvicola-1.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/silvicola\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Silvicola-1.jpg\" alt=\"silvicola\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Silvicola-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Silvicola-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8538 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_10 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Je-suis-la-riviere-la-riviere-est-moi-1.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/je-suis-la-riviere-la-riviere-est-moi\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Je-suis-la-riviere-la-riviere-est-moi-1.jpg\" alt=\"i am the river\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Je-suis-la-riviere-la-riviere-est-moi-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Je-suis-la-riviere-la-riviere-est-moi-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8536 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_11 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Plastic-Fantastic-1.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/plastic-fantastic\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Plastic-Fantastic-1.jpg\" alt=\"plastic fantastic\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Plastic-Fantastic-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Plastic-Fantastic-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8534 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element dnxte_coverflowslider_child dnxte_coverflowslider_child_12 et_clickable\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dnxte-coverflow-image-container\" data-image-position=\"\">\r\n                <span href=\"\/wp-content\/uploads\/2025\/01\/Lappel-de-la-nature-1.jpg\" class=\"dnxte-coverflow-image-link\" data-title=\"\" data-link=\"\/competition-internationale\/lappel-de-la-nature\/,_self\">\r\n                    <div class=\"dnxte-coverflow-overlay-color\"><\/div>\r\n                    <div class=\"dnxte-coverflow-overlay-color-hover\"><\/div>\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"565\" src=\"\/wp-content\/uploads\/2025\/01\/Lappel-de-la-nature-1.jpg\" alt=\"l&#039;appel de la nature\" title=\"\" srcset=\"https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Lappel-de-la-nature-1.jpg 400w, https:\/\/fifes.org\/wp-content\/uploads\/2025\/01\/Lappel-de-la-nature-1-212x300.jpg 212w\" sizes=\"(max-width: 400px) 100vw, 400px\" class=\"wp-image-8532 img-fluid\" \/>\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"dnxte-coverflow-multitext \">\r\n                \r\n                \r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\r\n                    <\/div>\r\n                    <div class=\"swiper-pagination swiper-pagination-clickable swiper-pagination-bullets swiper-pagination-bullets-dynamic mt-10\"><\/div>\r\n                <\/div>\r\n                \r\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":6486,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-10942","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Documerica, self-portrait of a nation on the brink of the abyss - Fifes - Festival Internation du Film Ecologique et Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fifes.org\/competition-internationale\/documerica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Documerica, self-portrait of a nation on the brink of the abyss - Fifes - Festival Internation du Film Ecologique et Social\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fifes.org\/competition-internationale\/documerica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fifes - Festival Internation du Film Ecologique et Social\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fifescannes\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T16:10:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fifes.org\\\/competition-internationale\\\/documerica\\\/\",\"url\":\"https:\\\/\\\/fifes.org\\\/competition-internationale\\\/documerica\\\/\",\"name\":\"Documerica, self-portrait of a nation on the brink of the abyss - Fifes - Festival Internation du Film Ecologique et Social\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fifes.org\\\/#website\"},\"datePublished\":\"2025-01-24T14:00:31+00:00\",\"dateModified\":\"2025-05-14T16:10:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fifes.org\\\/competition-internationale\\\/documerica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fifes.org\\\/competition-internationale\\\/documerica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fifes.org\\\/competition-internationale\\\/documerica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fifes.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"International competition\",\"item\":\"https:\\\/\\\/fifes.org\\\/en\\\/international-competition\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Documerica, self-portrait of a nation on the brink of the abyss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fifes.org\\\/#website\",\"url\":\"https:\\\/\\\/fifes.org\\\/\",\"name\":\"Fifes - Festival Internation du Film Ecologique et Social\",\"description\":\"Venez \u00e0 la rencontre d\u2019un festival qui vous ressemble et qui nous rassemble !\",\"publisher\":{\"@id\":\"https:\\\/\\\/fifes.org\\\/#organization\"},\"alternateName\":\"F.I.F.E.S.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fifes.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fifes.org\\\/#organization\",\"name\":\"Festival International du Film Ecologique et Social\",\"alternateName\":\"F.I.F.E.S.\",\"url\":\"https:\\\/\\\/fifes.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fifes.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fifes.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Logo-2023-480px-e1671803170434.png\",\"contentUrl\":\"https:\\\/\\\/fifes.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Logo-2023-480px-e1671803170434.png\",\"width\":200,\"height\":188,\"caption\":\"Festival International du Film Ecologique et Social\"},\"image\":{\"@id\":\"https:\\\/\\\/fifes.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fifescannes\",\"https:\\\/\\\/www.instagram.com\\\/fifescannes\\\/?hl=fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Documerica, self-portrait of a nation on the brink of the abyss - Fifes - Festival Internation du Film Ecologique et Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fifes.org\/competition-internationale\/documerica\/","og_locale":"en_US","og_type":"article","og_title":"Documerica, self-portrait of a nation on the brink of the abyss - Fifes - Festival Internation du Film Ecologique et Social","og_url":"https:\/\/fifes.org\/competition-internationale\/documerica\/","og_site_name":"Fifes - Festival Internation du Film Ecologique et Social","article_publisher":"https:\/\/www.facebook.com\/fifescannes","article_modified_time":"2025-05-14T16:10:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fifes.org\/competition-internationale\/documerica\/","url":"https:\/\/fifes.org\/competition-internationale\/documerica\/","name":"Documerica, self-portrait of a nation on the brink of the abyss - Fifes - Festival Internation du Film Ecologique et Social","isPartOf":{"@id":"https:\/\/fifes.org\/#website"},"datePublished":"2025-01-24T14:00:31+00:00","dateModified":"2025-05-14T16:10:34+00:00","breadcrumb":{"@id":"https:\/\/fifes.org\/competition-internationale\/documerica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fifes.org\/competition-internationale\/documerica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fifes.org\/competition-internationale\/documerica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fifes.org\/en\/"},{"@type":"ListItem","position":2,"name":"International competition","item":"https:\/\/fifes.org\/en\/international-competition\/"},{"@type":"ListItem","position":3,"name":"Documerica, self-portrait of a nation on the brink of the abyss"}]},{"@type":"WebSite","@id":"https:\/\/fifes.org\/#website","url":"https:\/\/fifes.org\/","name":"Fifes - Festival Internation du Film Ecologique et Social","description":"Venez \u00e0 la rencontre d\u2019un festival qui vous ressemble et qui nous rassemble !","publisher":{"@id":"https:\/\/fifes.org\/#organization"},"alternateName":"F.I.F.E.S.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fifes.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fifes.org\/#organization","name":"Festival International du Film Ecologique et Social","alternateName":"F.I.F.E.S.","url":"https:\/\/fifes.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fifes.org\/#\/schema\/logo\/image\/","url":"https:\/\/fifes.org\/wp-content\/uploads\/2022\/12\/Logo-2023-480px-e1671803170434.png","contentUrl":"https:\/\/fifes.org\/wp-content\/uploads\/2022\/12\/Logo-2023-480px-e1671803170434.png","width":200,"height":188,"caption":"Festival International du Film Ecologique et Social"},"image":{"@id":"https:\/\/fifes.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fifescannes","https:\/\/www.instagram.com\/fifescannes\/?hl=fr"]}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages\/10942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/comments?post=10942"}],"version-history":[{"count":2,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages\/10942\/revisions"}],"predecessor-version":[{"id":10944,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages\/10942\/revisions\/10944"}],"up":[{"embeddable":true,"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/pages\/6486"}],"wp:attachment":[{"href":"https:\/\/fifes.org\/en\/wp-json\/wp\/v2\/media?parent=10942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}